{"id":65000,"date":"2025-04-13T09:24:02","date_gmt":"2025-04-13T12:24:02","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=65000"},"modified":"2025-04-13T09:24:03","modified_gmt":"2025-04-13T12:24:03","slug":"paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/","title":{"rendered":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo"},"content":{"rendered":"\n<p>Em sua 56\u00aa edi\u00e7\u00e3o, a Paix\u00e3o de Cristo de Nova Jerusal\u00e9m abriu suas portas para a pr\u00e9-estreia nesta sexta-feira (11), com a presen\u00e7a da governadora Raquel Lyra e da vice-governadora Priscila Krause. Durante o espet\u00e1culo, que acontece no distrito de Fazenda Nova, no munic\u00edpio de Brejo da Madre de Deus, Agreste Central, a governadora destacou a import\u00e2ncia do evento, considerado o maior teatro ao ar livre do mundo, como s\u00edmbolo da for\u00e7a da cultura pernambucana e de tradi\u00e7\u00e3o no turismo.<\/p>\n\n\n\n<p><br>&#8220;Estamos todos juntos aqui para manter nossa tradi\u00e7\u00e3o e, mais do que isso, fortalecer a nossa economia, cultura e o turismo. Estamos come\u00e7ando a temporada da Paix\u00e3o de Cristo, onde Pernambuco abre os bra\u00e7os para receber as pessoas nesse local tur\u00edstico. O Governo de Pernambuco vem trabalhando muito para apoiar esse espet\u00e1culo e toda a cultura pernambucana. Pelo terceiro ano consecutivo estamos aqui para poder divulgar um evento t\u00e3o lindo como esse&#8221;, registrou a governadora.<\/p>\n\n\n\n<p><br>A edi\u00e7\u00e3o deste ano conta novamente com o apoio do Governo de Pernambuco, por meio da Empresa de Turismo de Pernambuco (Empetur). O investimento refor\u00e7a o compromisso da atual gest\u00e3o com a valoriza\u00e7\u00e3o de eventos que impulsionam a economia criativa e o turismo nas diferentes regi\u00f5es do estado.\u00a0<\/p>\n\n\n\n<p><br>De acordo com o secret\u00e1rio de Turismo e Lazer, Kaio Mani\u00e7oba, o investimento movimenta todo o Agreste. \u201c\u00c9 um momento em que Pernambuco \u00e9 visto para o mundo todo. Atrai turistas de outros estados, do mundo, e a gente se orgulha muito. O aumento de p\u00fablico, o aumento tamb\u00e9m de passageiros no aeroporto, mostram a for\u00e7a do espet\u00e1culo. Ent\u00e3o, s\u00e3o atrativos como esse que Pernambuco fortalece para que o turista possa vir mais vezes\u201d, disse o secret\u00e1rio.<\/p>\n\n\n\n<p><br>A temporada 2025 da Paix\u00e3o de Cristo tem in\u00edcio neste s\u00e1bado (12) e segue at\u00e9 o Domingo de P\u00e1scoa, 20 de abril. Com 56 anos de hist\u00f3ria, o espet\u00e1culo \u00e9 encenado dentro da cidade-teatro de Nova Jerusal\u00e9m, uma estrutura monumental cercada por muralhas de pedra e torres que reproduzem ambientes b\u00edblicos com realismo.<\/p>\n\n\n\n<p><br>O coordenador geral da Paix\u00e3o de Cristo, Robinson Pacheco, celebrou o in\u00edcio da temporada com otimismo. \u201cS\u00e3o 56 anos de espet\u00e1culo, mas tudo dentro do programado, tudo dentro do planejamento. Estamos aqui na pr\u00e9-estreia, com a presen\u00e7a da governadora Raquel Lyra e mais convidados, e estamos muito felizes e crentes que vamos ter uma temporada de pleno sucesso\u201d, afirmou.<\/p>\n\n\n\n<p><br><strong>SEGURAN\u00c7A REFOR\u00c7ADA &#8211;<\/strong>\u00a0Para garantir a tranquilidade da popula\u00e7\u00e3o durante a Semana Santa, a Secretaria de Defesa Social (SDS) colocou em pr\u00e1tica uma opera\u00e7\u00e3o especial que come\u00e7ou nesta sexta (11) e segue at\u00e9 20 de abril. Com investimento de R$ 1,4 milh\u00e3o, as for\u00e7as de seguran\u00e7a v\u00e3o lan\u00e7ar 8.054 jornadas extras de trabalho, um aumento de 10,8% no efetivo em rela\u00e7\u00e3o ao ano anterior. Os efetivos empregados s\u00e3o de policiais civis e militares, profissionais do Corpo de Bombeiros, da Pol\u00edcia Cient\u00edfica, entre outras operativas.<\/p>\n\n\n\n<p><br><strong>OPERA\u00c7\u00c3O LEI SECA &#8211;<\/strong><\/p>\n\n\n\n<p>\u00a0Tamb\u00e9m ser\u00e1 intensificada a Opera\u00e7\u00e3o Lei Seca (OLS) em Pernambuco ao longo da Semana Santa, a partir deste s\u00e1bado (12). Est\u00e3o previstas 54 blitze e 12 a\u00e7\u00f5es educativas, com atua\u00e7\u00e3o em polos estrat\u00e9gicos como Brejo da Madre de Deus, Gravat\u00e1, Caruaru, litoral e Regi\u00e3o Metropolitana do Recife.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua 56\u00aa edi\u00e7\u00e3o, a Paix\u00e3o de Cristo de Nova Jerusal\u00e9m abriu suas portas para a pr\u00e9-estreia nesta sexta-feira (11),<\/p>\n","protected":false},"author":2,"featured_media":65001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[],"class_list":["post-65000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pernambuco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"Em sua 56\u00aa edi\u00e7\u00e3o, a Paix\u00e3o de Cristo de Nova Jerusal\u00e9m abriu suas portas para a pr\u00e9-estreia nesta sexta-feira (11),\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-13T12:24:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-13T12:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo\",\"datePublished\":\"2025-04-13T12:24:02+00:00\",\"dateModified\":\"2025-04-13T12:24:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1\",\"articleSection\":[\"Pernambuco\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/\",\"name\":\"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1\",\"datePublished\":\"2025-04-13T12:24:02+00:00\",\"dateModified\":\"2025-04-13T12:24:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1\",\"width\":1280,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/","og_locale":"pt_BR","og_type":"article","og_title":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM","og_description":"Em sua 56\u00aa edi\u00e7\u00e3o, a Paix\u00e3o de Cristo de Nova Jerusal\u00e9m abriu suas portas para a pr\u00e9-estreia nesta sexta-feira (11),","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/","og_site_name":"Afogados FM","article_published_time":"2025-04-13T12:24:02+00:00","article_modified_time":"2025-04-13T12:24:03+00:00","og_image":[{"width":1280,"height":852,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg","type":"image\/jpeg"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo","datePublished":"2025-04-13T12:24:02+00:00","dateModified":"2025-04-13T12:24:03+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1","articleSection":["Pernambuco"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/","name":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1","datePublished":"2025-04-13T12:24:02+00:00","dateModified":"2025-04-13T12:24:03+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1","width":1280,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/paixao-de-cristo-de-nova-jerusalem-governadora-raquel-lyra-destaca-tradicao-turistica-e-cultural-do-espetaculo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"Paix\u00e3o de Cristo de Nova Jerusal\u00e9m: Governadora Raquel Lyra destaca tradi\u00e7\u00e3o tur\u00edstica e cultural do espet\u00e1culo"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/Janaina-Pepeu_Secom-2.jpeg?fit=1280%2C852&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=65000"}],"version-history":[{"count":1,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65000\/revisions"}],"predecessor-version":[{"id":65002,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65000\/revisions\/65002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/65001"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=65000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=65000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=65000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}