{"id":65003,"date":"2025-04-13T09:27:34","date_gmt":"2025-04-13T12:27:34","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=65003"},"modified":"2025-04-13T09:36:33","modified_gmt":"2025-04-13T12:36:33","slug":"bolsonaro-tem-melhora-e-sera-transferido-para-brasilia","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/","title":{"rendered":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia"},"content":{"rendered":"\n<p>O ex-presidente Jair Bolsonaro chegou a Bras\u00edlia no s\u00e1bado em um avi\u00e3o m\u00e9dico vindo de Natal e foi para um hospital onde disse que &#8220;provavelmente&#8221; passaria por uma cirurgia ap\u00f3s sentir fortes dores abdominais.<\/p>\n\n\n\n<p>&#8220;Ap\u00f3s a minha transfer\u00eancia, provavelmente passarei por uma nova cirurgia&#8221;, indicou mais cedo no X o ex-presidente, operado v\u00e1rias vezes nos \u00faltimos anos devido a sequelas do ataque a faca que sofreu em setembro de 2018. Ele revelou que, segundo seu m\u00e9dico, &#8220;este foi o quadro mais grave desde o atentado&#8221;.<\/p>\n\n\n\n<p>&#8220;Depois de tantos epis\u00f3dios semelhantes ao longo dos \u00faltimos anos, fui me acostumando com a dor e com o desconforto. Mas, desta vez, at\u00e9 os m\u00e9dicos se surpreenderam&#8221;, comentou Bolsonaro, ao destacar que est\u00e1 &#8220;est\u00e1vel, em recupera\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<p>&#8220;Sua sa\u00fade n\u00e3o piorou, est\u00e1 est\u00e1vel. Mas \u00e9 necess\u00e1ria uma cirurgia para resolver a crise&#8221;, acrescentou \u00e0 AFP Rog\u00e9rio Marinho, senador pelo PL, que acompanhou ontem o ex-presidente em um giro pol\u00edtico que os levou a v\u00e1rias cidades do Rio Grande do Norte.<\/p>\n\n\n\n<p>Horas antes, em coletiva de imprensa no Hospital do Rio Grande, o m\u00e9dico de Bolsonaro, Cl\u00e1udio Birolini, havia indicado que &#8220;este epis\u00f3dio atual parece um pouco mais exuberante do que os epis\u00f3dios anteriores, sobretudo o intestinal&#8221;.<\/p>\n\n\n\n<p>O ex-presidente deixou o hospital por volta das 17h30, usando uma sonda nasal. Antes de entrar na ambul\u00e2ncia, cumprimentou dezenas de apoiadores, a maioria vestida de verde e amarelo.<\/p>\n\n\n\n<p>Segundo boletim m\u00e9dico divulgado ao meio-dia, o estado de sa\u00fade de Bolsonaro evolui de forma est\u00e1vel e ele se encontra em excelente estado de \u00e2nimo, ap\u00f3s passar uma noite tranquila.<\/p>\n\n\n\n<p>O giro pelo Rio Grande do Norte foi interrompido ontem devido \u00e0s dores do ex-presidente. A viagem era realizada duas semanas depois de Bolsonaro ser indiciado pelo STF por tentativa de golpe de Estado.<\/p>\n\n\n\n<p>Bolsonaro est\u00e1 impedido de disputar elei\u00e7\u00f5es at\u00e9 2030 por ter questionado, sem apresentar provas, a confiabilidade do sistema eleitoral. Ele tamb\u00e9m ser\u00e1 julgado por uma suposta tentativa de golpe de Estado ap\u00f3s as elei\u00e7\u00f5es de outubro de 2022, nas quais foi derrotado por Luiz In\u00e1cio Lula da Silva (PT).<\/p>\n\n\n\n<p>Se for considerado culpado no julgamento, previsto para os pr\u00f3ximos meses, ele poder\u00e1 pegar at\u00e9 40 anos de pris\u00e3o. Segundo a Procuradoria-Geral da Rep\u00fablica, Bolsonaro teria buscado o apoio das For\u00e7as Armadas para impedir a posse de Lula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-presidente Jair Bolsonaro chegou a Bras\u00edlia no s\u00e1bado em um avi\u00e3o m\u00e9dico vindo de Natal e foi para um<\/p>\n","protected":false},"author":2,"featured_media":64973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-65003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"O ex-presidente Jair Bolsonaro chegou a Bras\u00edlia no s\u00e1bado em um avi\u00e3o m\u00e9dico vindo de Natal e foi para um\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-13T12:27:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-13T12:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1056\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"Bolsonaro tem melhora e foi transferido para Bras\u00edlia\",\"datePublished\":\"2025-04-13T12:27:34+00:00\",\"dateModified\":\"2025-04-13T12:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bolsointt.jpg?fit=1056%2C836&ssl=1\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/\",\"name\":\"Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bolsointt.jpg?fit=1056%2C836&ssl=1\",\"datePublished\":\"2025-04-13T12:27:34+00:00\",\"dateModified\":\"2025-04-13T12:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bolsointt.jpg?fit=1056%2C836&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bolsointt.jpg?fit=1056%2C836&ssl=1\",\"width\":1056,\"height\":836},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/04\\\/13\\\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsonaro tem melhora e foi transferido para Bras\u00edlia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/","og_locale":"pt_BR","og_type":"article","og_title":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM","og_description":"O ex-presidente Jair Bolsonaro chegou a Bras\u00edlia no s\u00e1bado em um avi\u00e3o m\u00e9dico vindo de Natal e foi para um","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/","og_site_name":"Afogados FM","article_published_time":"2025-04-13T12:27:34+00:00","article_modified_time":"2025-04-13T12:36:33+00:00","og_image":[{"width":1056,"height":836,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg","type":"image\/jpeg"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia","datePublished":"2025-04-13T12:27:34+00:00","dateModified":"2025-04-13T12:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg?fit=1056%2C836&ssl=1","articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/","name":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg?fit=1056%2C836&ssl=1","datePublished":"2025-04-13T12:27:34+00:00","dateModified":"2025-04-13T12:36:33+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg?fit=1056%2C836&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg?fit=1056%2C836&ssl=1","width":1056,"height":836},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/04\/13\/bolsonaro-tem-melhora-e-sera-transferido-para-brasilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"Bolsonaro tem melhora e foi transferido para Bras\u00edlia"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/04\/bolsointt.jpg?fit=1056%2C836&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=65003"}],"version-history":[{"count":2,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65003\/revisions"}],"predecessor-version":[{"id":65008,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/65003\/revisions\/65008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/64973"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=65003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=65003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=65003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}