{"id":71698,"date":"2025-12-31T06:10:34","date_gmt":"2025-12-31T09:10:34","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=71698"},"modified":"2025-12-31T06:10:35","modified_gmt":"2025-12-31T09:10:35","slug":"portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/","title":{"rendered":"Portaria do governo define feriados e pontos facultativos de 2026"},"content":{"rendered":"\n<p>Dos dez feriados nacionais de 2026, apenas um cai no fim de semana: o da Proclama\u00e7\u00e3o da Rep\u00fablica, em 15 de novembro, um domingo. A informa\u00e7\u00e3o est\u00e1 na portaria desta ter\u00e7a-feira (30) do Minist\u00e9rio da Gest\u00e3o e da Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos (MGI), onde tamb\u00e9m constam os nove pontos facultativos do novo ano.<\/p>\n\n\n\n<p>As datas, segundo a publica\u00e7\u00e3o, devem ser observadas pelos \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o p\u00fablica federal direta, pelas autarquias e pelas funda\u00e7\u00f5es, sem comprometer os servi\u00e7os essenciais \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>A lista inclui datas do calend\u00e1rio religioso brasileiro, como o feriado nacional da Paix\u00e3o de Cristo, em 3 de abril, al\u00e9m de per\u00edodos de organiza\u00e7\u00e3o do funcionamento administrativo, como os pontos facultativos do carnaval, em 16 e 17 de fevereiro.<\/p>\n\n\n\n<p>A portaria tamb\u00e9m determina que os \u00f3rg\u00e3os federais, como minist\u00e9rios, autarquias e funda\u00e7\u00f5es, devem seguir os feriados que celebram o fato hist\u00f3rico mais importante de cada estado, a chamada \u201cdata magna\u201d, definida em lei estadual. Tamb\u00e9m devem respeitar os feriados que marcam os 100 anos de funda\u00e7\u00e3o de cada munic\u00edpio, quando essas datas estiverem previstas em lei municipal.<\/p>\n\n\n\n<p><em>Com informa\u00e7\u00f5es da Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos dez feriados nacionais de 2026, apenas um cai no fim de semana: o da Proclama\u00e7\u00e3o da Rep\u00fablica, em 15<\/p>\n","protected":false},"author":2,"featured_media":71699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-71698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"Dos dez feriados nacionais de 2026, apenas um cai no fim de semana: o da Proclama\u00e7\u00e3o da Rep\u00fablica, em 15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-31T09:10:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T09:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"Portaria do governo define feriados e pontos facultativos de 2026\",\"datePublished\":\"2025-12-31T09:10:34+00:00\",\"dateModified\":\"2025-12-31T09:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/\",\"name\":\"Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1\",\"datePublished\":\"2025-12-31T09:10:34+00:00\",\"dateModified\":\"2025-12-31T09:10:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2025\\\/12\\\/31\\\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portaria do governo define feriados e pontos facultativos de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM","og_description":"Dos dez feriados nacionais de 2026, apenas um cai no fim de semana: o da Proclama\u00e7\u00e3o da Rep\u00fablica, em 15","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/","og_site_name":"Afogados FM","article_published_time":"2025-12-31T09:10:34+00:00","article_modified_time":"2025-12-31T09:10:35+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp","type":"image\/webp"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"Portaria do governo define feriados e pontos facultativos de 2026","datePublished":"2025-12-31T09:10:34+00:00","dateModified":"2025-12-31T09:10:35+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1","articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/","name":"Portaria do governo define feriados e pontos facultativos de 2026 - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1","datePublished":"2025-12-31T09:10:34+00:00","dateModified":"2025-12-31T09:10:35+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2025\/12\/31\/portaria-do-governo-define-feriados-e-pontos-facultativos-de-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"Portaria do governo define feriados e pontos facultativos de 2026"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2025\/12\/mosaico_feriados_dsc6584.webp?fit=1170%2C700&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/71698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=71698"}],"version-history":[{"count":1,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/71698\/revisions"}],"predecessor-version":[{"id":71700,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/71698\/revisions\/71700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/71699"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=71698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=71698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=71698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}