{"id":73596,"date":"2026-04-04T07:26:42","date_gmt":"2026-04-04T10:26:42","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=73596"},"modified":"2026-04-06T07:29:25","modified_gmt":"2026-04-06T10:29:25","slug":"conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/","title":{"rendered":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz"},"content":{"rendered":"<p>O Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas deve votar, na pr\u00f3xima semana, uma resolu\u00e7\u00e3o sobre o uso da for\u00e7a para proteger a navega\u00e7\u00e3o comercial no Estreito de Ormuz.<\/p>\n<p>A reuni\u00e3o foi remarcada ap\u00f3s adiamentos nesta sexta-feira e neste s\u00e1bado, mas ainda sem nova data anunciada. Diplomatas envolvidos no tema avaliam, no entanto, que a vota\u00e7\u00e3o pode ocorrer semana que vem.<\/p>\n<p>O Estreito de Ormuz \u00e9 a principal rota mar\u00edtima de petr\u00f3leo do mundo e concentra cerca de um quinto do consumo global da commodity.<\/p>\n<p>A regi\u00e3o vive sob forte tens\u00e3o, com o Ir\u00e3 amea\u00e7ando restringir a passagem em meio a conflitos com os Estados Unidos e Israel.<\/p>\n<p>A proposta apresentada pelo Bahrein autoriza o uso de todos os meios defensivos necess\u00e1rios para proteger a navega\u00e7\u00e3o comercial.<\/p>\n<p>Segundo o texto final, a medida poderia ser adotada \u201cpor um per\u00edodo de pelo menos seis meses&#8230; e at\u00e9 que o Conselho decida o contr\u00e1rio\u201d.<\/p>\n<p>A resolu\u00e7\u00e3o enfrenta resist\u00eancia da R\u00fassia, Fran\u00e7a e China.<\/p>\n<p>Mas Estados Unidos e Reino Unidos devem votar a favor.<\/p>\n<p>Para ser aprovada, a resolu\u00e7\u00e3o precisa de pelo menos nove votos favor\u00e1veis e n\u00e3o pode sofrer veto de nenhum dos cinco membros permanentes: Reino Unido, China, Fran\u00e7a, R\u00fassia e Estados Unidos.<\/p>\n<p>O presidente dos Estados Unidos, Donald Trump, afirmou que pretende continuar os ataques ao Ir\u00e3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas deve votar, na pr\u00f3xima semana, uma resolu\u00e7\u00e3o sobre o uso da for\u00e7a para<\/p>\n","protected":false},"author":2,"featured_media":73598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-73596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"O Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas deve votar, na pr\u00f3xima semana, uma resolu\u00e7\u00e3o sobre o uso da for\u00e7a para\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-04T10:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T10:29:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"281\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz\",\"datePublished\":\"2026-04-04T10:26:42+00:00\",\"dateModified\":\"2026-04-06T10:29:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/OIP.webp?fit=281%2C180&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/\",\"name\":\"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/OIP.webp?fit=281%2C180&ssl=1\",\"datePublished\":\"2026-04-04T10:26:42+00:00\",\"dateModified\":\"2026-04-06T10:29:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/OIP.webp?fit=281%2C180&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/OIP.webp?fit=281%2C180&ssl=1\",\"width\":281,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/04\\\/04\\\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/","og_locale":"pt_BR","og_type":"article","og_title":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM","og_description":"O Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas deve votar, na pr\u00f3xima semana, uma resolu\u00e7\u00e3o sobre o uso da for\u00e7a para","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/","og_site_name":"Afogados FM","article_published_time":"2026-04-04T10:26:42+00:00","article_modified_time":"2026-04-06T10:29:25+00:00","og_image":[{"width":281,"height":180,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp","type":"image\/webp"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz","datePublished":"2026-04-04T10:26:42+00:00","dateModified":"2026-04-06T10:29:25+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp?fit=281%2C180&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/","name":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp?fit=281%2C180&ssl=1","datePublished":"2026-04-04T10:26:42+00:00","dateModified":"2026-04-06T10:29:25+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp?fit=281%2C180&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp?fit=281%2C180&ssl=1","width":281,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/04\/04\/conselho-de-seguranca-da-onu-vota-resolucao-sobre-estreito-de-ormuz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"Conselho de Seguran\u00e7a da ONU vota resolu\u00e7\u00e3o sobre estreito de Ormuz"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/04\/OIP.webp?fit=281%2C180&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/73596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=73596"}],"version-history":[{"count":1,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/73596\/revisions"}],"predecessor-version":[{"id":73597,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/73596\/revisions\/73597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/73598"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=73596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=73596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=73596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}