{"id":74943,"date":"2026-07-15T08:38:23","date_gmt":"2026-07-15T11:38:23","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=74943"},"modified":"2026-07-15T08:38:23","modified_gmt":"2026-07-15T11:38:23","slug":"ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/","title":{"rendered":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es"},"content":{"rendered":"<p class=\"isSelectedEnd\">O cen\u00e1rio pol\u00edtico de Afogados da Ingazeira ganhou um novo cap\u00edtulo neste fim de semana com a decis\u00e3o do ex-vereador\u00a0<strong>Toinho da Ponte<\/strong>\u00a0de integrar o grupo de oposi\u00e7\u00e3o liderado pelo pr\u00e9-candidato a deputado federal\u00a0<strong>Danilo Sim\u00f5es<\/strong>. Al\u00e9m de anunciar apoio ao projeto de Danilo para a C\u00e2mara Federal, Toinho tamb\u00e9m confirmou que estar\u00e1 ao lado do ex-prefeito de Flores,\u00a0<strong>Marconi Santana<\/strong>, em sua pr\u00e9-candidatura a deputado estadual.<\/p>\n<p class=\"isSelectedEnd\">A ades\u00e3o \u00e9 vista como mais um refor\u00e7o para o bloco de oposi\u00e7\u00e3o no munic\u00edpio e movimenta os bastidores da pol\u00edtica afogadense \u00e0s v\u00e9speras das articula\u00e7\u00f5es para as elei\u00e7\u00f5es de 2026.<\/p>\n<p class=\"isSelectedEnd\">Segundo informa\u00e7\u00f5es divulgadas nos bastidores pol\u00edticos, o rompimento de Toinho da Ponte com o grupo governista teria ocorrido ap\u00f3s o ex-vereador n\u00e3o conseguir o atendimento de demandas que vinha apresentando \u00e0 atual gest\u00e3o municipal. Ainda conforme as informa\u00e7\u00f5es, o principal motivo de insatisfa\u00e7\u00e3o seria a falta de aten\u00e7\u00e3o dada aos seus pleitos por parte dos secret\u00e1rios municipais\u00a0<strong>Od\u00edlio Lopes<\/strong>\u00a0e\u00a0<strong>Valberto Amaral<\/strong>, situa\u00e7\u00e3o que teria levado ao desgaste da rela\u00e7\u00e3o pol\u00edtica.<\/p>\n<p>Com a mudan\u00e7a de posicionamento, Toinho da Ponte passa a apoiar oficialmente\u00a0<strong>Danilo Sim\u00f5es<\/strong>\u00a0na disputa por uma vaga na C\u00e2mara dos Deputados e\u00a0<strong>Marconi Santana<\/strong>\u00a0na corrida por uma cadeira na Assembleia Legislativa de Pernambuco (Alepe).<\/p>\n<p>Do Cau\u00ea Rodrigues<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cen\u00e1rio pol\u00edtico de Afogados da Ingazeira ganhou um novo cap\u00edtulo neste fim de semana com a decis\u00e3o do ex-vereador\u00a0Toinho<\/p>\n","protected":false},"author":2,"featured_media":74944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[35],"tags":[],"class_list":["post-74943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"O cen\u00e1rio pol\u00edtico de Afogados da Ingazeira ganhou um novo cap\u00edtulo neste fim de semana com a decis\u00e3o do ex-vereador\u00a0Toinho\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T11:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es\",\"datePublished\":\"2026-07-15T11:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/\",\"name\":\"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1\",\"datePublished\":\"2026-07-15T11:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1\",\"width\":958,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/07\\\/15\\\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM","og_description":"O cen\u00e1rio pol\u00edtico de Afogados da Ingazeira ganhou um novo cap\u00edtulo neste fim de semana com a decis\u00e3o do ex-vereador\u00a0Toinho","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/","og_site_name":"Afogados FM","article_published_time":"2026-07-15T11:38:23+00:00","og_image":[{"width":958,"height":770,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp","type":"image\/webp"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es","datePublished":"2026-07-15T11:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1","articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/","name":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1","datePublished":"2026-07-15T11:38:23+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1","width":958,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/07\/15\/ex-vereador-toinho-da-ponte-declara-apoio-a-marconi-santana-e-danilo-simoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"Ex-vereador Toinho da Ponte declara apoio a Marconi Santana e Danilo Sim\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-12.18.46.webp?fit=958%2C770&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/74943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=74943"}],"version-history":[{"count":1,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/74943\/revisions"}],"predecessor-version":[{"id":74945,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/74943\/revisions\/74945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/74944"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=74943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=74943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=74943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}