{"id":75627,"date":"2026-09-02T05:55:33","date_gmt":"2026-09-02T08:55:33","guid":{"rendered":"https:\/\/afogadosfm.com.br\/afogadosfm\/?p=75627"},"modified":"2026-09-02T05:55:33","modified_gmt":"2026-09-02T08:55:33","slug":"pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes","status":"publish","type":"post","link":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/","title":{"rendered":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes"},"content":{"rendered":"<p>O procurador-geral da Rep\u00fablica, Paulo Gonet, pediu ao Supremo Tribunal Federal a anula\u00e7\u00e3o de parte da investiga\u00e7\u00e3o da Pol\u00edcia Federal que revelou troca de mensagens entre o ministro do STF Alexandre de Moraes e o ex-banqueiro Daniel Vorcaro. O parecer foi enviado nesta ter\u00e7a-feira (1) ao relator do caso, ministro Andr\u00e9 Mendon\u00e7a.<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=840&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=840&#038;ssl=1\" \/><\/p>\n<p>Segundo Gonet, Mendon\u00e7a agiu de forma irregular ao determinar, por conta pr\u00f3pria, que a Pol\u00edcia Federal aprofundasse as investiga\u00e7\u00f5es sobre as conversas entre Moraes e Vorcaro, no \u00e2mbito do caso do Banco Master. Para o procurador, esse tipo de decis\u00e3o poderia partir somente do plen\u00e1rio do Supremo \u2014 e n\u00e3o de um \u00fanico ministro, agindo sozinho, na fase que antecede a abertura de um processo formal.<\/p>\n<p>O procurador defende que, havendo suspeita contra Moraes, o caminho correto seria informar o presidente da Corte, Edson Fachin, que levaria o assunto ao colegiado. Para Gonet, ao repassar a ordem diretamente \u00e0 Pol\u00edcia Federal, Mendon\u00e7a ultrapassou os limites da pr\u00f3pria fun\u00e7\u00e3o dentro da investiga\u00e7\u00e3o.<\/p>\n<p>As men\u00e7\u00f5es a Moraes e ao pr\u00f3prio Gonet vieram \u00e0 tona depois que a Pol\u00edcia Federal quebrou o sigilo do celular de Vorcaro, alvo da Opera\u00e7\u00e3o Compliance Zero, que apura fraudes financeiras no Banco Master. O sigilo do relat\u00f3rio da investiga\u00e7\u00e3o foi derrubado nesta ter\u00e7a-feira.<\/p>\n<p>O parecer da Procuradoria-Geral da Rep\u00fablica atendeu a um pedido do pr\u00f3prio Mendon\u00e7a, que havia solicitado \u00e0 PGR uma manifesta\u00e7\u00e3o sobre o conte\u00fado do relat\u00f3rio policial antes de decidir os pr\u00f3ximos passos do caso.<\/p>\n<p><em>Com informa\u00e7\u00f5es da Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O procurador-geral da Rep\u00fablica, Paulo Gonet, pediu ao Supremo Tribunal Federal a anula\u00e7\u00e3o de parte da investiga\u00e7\u00e3o da Pol\u00edcia Federal<\/p>\n","protected":false},"author":2,"featured_media":33252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-75627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM\" \/>\n<meta property=\"og:description\" content=\"O procurador-geral da Rep\u00fablica, Paulo Gonet, pediu ao Supremo Tribunal Federal a anula\u00e7\u00e3o de parte da investiga\u00e7\u00e3o da Pol\u00edcia Federal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/\" \/>\n<meta property=\"og:site_name\" content=\"Afogados FM\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T08:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afogadosfm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afogadosfm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/\"},\"author\":{\"name\":\"afogadosfm\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\"},\"headline\":\"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes\",\"datePublished\":\"2026-09-02T08:55:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pgr.jpg?fit=1100%2C600&ssl=1\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/\",\"name\":\"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pgr.jpg?fit=1100%2C600&ssl=1\",\"datePublished\":\"2026-09-02T08:55:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pgr.jpg?fit=1100%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pgr.jpg?fit=1100%2C600&ssl=1\",\"width\":1100,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/2026\\\/09\\\/02\\\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#website\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"name\":\"Afogados FM\",\"description\":\"Um site completo!\",\"publisher\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#organization\",\"name\":\"Afogados FM\",\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/afogadosfm.com.br\\\/afogadosfm\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1\",\"width\":369,\"height\":137,\"caption\":\"Afogados FM\"},\"image\":{\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/#\\\/schema\\\/person\\\/60e56f2cf5dc960fc093fe093d9e9057\",\"name\":\"afogadosfm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"afogadosfm\"},\"url\":\"https:\\\/\\\/afogadosfm.com.br\\\/afogadosfm\\\/author\\\/afogadosfm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/","og_locale":"pt_BR","og_type":"article","og_title":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM","og_description":"O procurador-geral da Rep\u00fablica, Paulo Gonet, pediu ao Supremo Tribunal Federal a anula\u00e7\u00e3o de parte da investiga\u00e7\u00e3o da Pol\u00edcia Federal","og_url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/","og_site_name":"Afogados FM","article_published_time":"2026-09-02T08:55:33+00:00","og_image":[{"width":1100,"height":600,"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg","type":"image\/jpeg"}],"author":"afogadosfm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afogadosfm","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#article","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/"},"author":{"name":"afogadosfm","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057"},"headline":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes","datePublished":"2026-09-02T08:55:33+00:00","mainEntityOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg?fit=1100%2C600&ssl=1","articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/","name":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes - Afogados FM","isPartOf":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#primaryimage"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg?fit=1100%2C600&ssl=1","datePublished":"2026-09-02T08:55:33+00:00","breadcrumb":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#primaryimage","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg?fit=1100%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg?fit=1100%2C600&ssl=1","width":1100,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/2026\/09\/02\/pgr-pede-que-stf-anule-investigacao-de-conversa-entre-vorcaro-e-moraes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/afogadosfm.com.br\/afogadosfm\/"},{"@type":"ListItem","position":2,"name":"PGR pede que STF anule investiga\u00e7\u00e3o de conversa entre Vorcaro e Moraes"}]},{"@type":"WebSite","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#website","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","name":"Afogados FM","description":"Um site completo!","publisher":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afogadosfm.com.br\/afogadosfm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#organization","name":"Afogados FM","url":"https:\/\/afogadosfm.com.br\/afogadosfm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","contentUrl":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2020\/06\/cropped-banner-afogados-4.jpg?fit=369%2C137&ssl=1","width":369,"height":137,"caption":"Afogados FM"},"image":{"@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afogadosfm.com.br\/afogadosfm\/#\/schema\/person\/60e56f2cf5dc960fc093fe093d9e9057","name":"afogadosfm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"afogadosfm"},"url":"https:\/\/afogadosfm.com.br\/afogadosfm\/author\/afogadosfm\/"}]}},"jetpack_publicize_connections":[],"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/afogadosfm.com.br\/afogadosfm\/wp-content\/uploads\/2021\/12\/pgr.jpg?fit=1100%2C600&ssl=1","_links":{"self":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/75627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/comments?post=75627"}],"version-history":[{"count":1,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/75627\/revisions"}],"predecessor-version":[{"id":75628,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/posts\/75627\/revisions\/75628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media\/33252"}],"wp:attachment":[{"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/media?parent=75627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/categories?post=75627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afogadosfm.com.br\/afogadosfm\/wp-json\/wp\/v2\/tags?post=75627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}